{"id":8783,"date":"2022-11-23T14:10:57","date_gmt":"2022-11-23T14:10:57","guid":{"rendered":"https:\/\/www.aromeprod2.com\/?p=8783"},"modified":"2024-03-28T13:40:52","modified_gmt":"2024-03-28T13:40:52","slug":"zucchini-tian-mit-ziegenkaese-und-pesto","status":"publish","type":"post","link":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/","title":{"rendered":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou"},"content":{"rendered":"<p><em>Von Colette, Lausanne<\/em><\/p>\n<p><strong>Zutaten (f\u00fcr 4 Personen) :<\/strong><\/p>\n<p>&#8211; Ein Pfund Zucchini<\/p>\n<p>&#8211; 2 frische Ziegen (am besten handwerklich)<\/p>\n<p>&#8211; 1 Glas Basilikum-Pistou 130g<br \/>\n&#8211; Salz, Pfeffer<\/p>\n<p><strong>Zubereitung des Rezepts :<\/strong><\/p>\n<p>&#8211; Sch\u00e4len und waschen Sie die Zucchini und schneiden Sie sie in dicke Scheiben.<\/p>\n<p>&#8211; 4\/5min d\u00e4mpfen und beiseite stellen.<\/p>\n<p>&#8211; Schneiden Sie den Frischk\u00e4se in Scheiben.<\/p>\n<p>&#8211; Die Zucchini mit dem K\u00e4se darauf legen.<\/p>\n<p>&#8211; Mit Basilikum-Pistou bestreuen.<\/p>\n<p>&#8211; Nach Belieben mit Salz und Pfeffer w\u00fcrzen.<\/p>\n<p>&#8211; Hei\u00df oder lauwarm genie\u00dfen<\/p>\n<p>&#8211;<\/p>\n<p><em><strong>Guten Appetit!<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h4>Zugeh\u00f6riges Produkt :<\/h4>\n<blockquote class=\"wp-embedded-content\" data-secret=\"mNi8U9xayK\"><p><a href=\"https:\/\/www.lesdelicesdeprovence.ch\/produits\/pistou-de-basilic\/\">Pistou de basilic genovese D.O.P<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Pistou de basilic genovese D.O.P&#8220; &#8212; Les D\u00e9lices de Provence\" src=\"https:\/\/www.lesdelicesdeprovence.ch\/produits\/pistou-de-basilic\/embed\/#?secret=JJGgeUWXTn#?secret=mNi8U9xayK\" data-secret=\"mNi8U9xayK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : &#8211; Ein Pfund Zucchini &#8211; 2 frische Ziegen (am besten handwerklich) &#8211; 1 Glas Basilikum-Pistou 130g &#8211; Salz, Pfeffer Zubereitung des Rezepts : &#8211; Sch\u00e4len und waschen Sie die Zucchini und schneiden Sie sie in dicke Scheiben. &#8211; 4\/5min d\u00e4mpfen und beiseite stellen. &#8211; Schneiden Sie den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[336,338],"tags":[641],"class_list":["post-8783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezept","category-salzig","tag-basilikumstempel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence<\/title>\n<meta name=\"description\" content=\"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence\" \/>\n<meta property=\"og:description\" content=\"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\" \/>\n<meta property=\"og:site_name\" content=\"Les D\u00e9lices de Provence\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T14:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T13:40:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"422\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Delices_Provence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Delices_Provence\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\"},\"author\":{\"name\":\"Delices_Provence\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616\"},\"headline\":\"Zucchini-Tian mit Ziegenk\u00e4se und Pistou\",\"datePublished\":\"2022-11-23T14:10:57+00:00\",\"dateModified\":\"2024-03-28T13:40:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\"},\"wordCount\":104,\"image\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg\",\"keywords\":[\"Basilikumstempel\"],\"articleSection\":[\"Rezept\",\"salzig\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\",\"url\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\",\"name\":\"Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg\",\"datePublished\":\"2022-11-23T14:10:57+00:00\",\"dateModified\":\"2024-03-28T13:40:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616\"},\"description\":\"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage\",\"url\":\"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg\",\"contentUrl\":\"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg\",\"width\":422,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accoglienza\",\"item\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zucchini-Tian mit Ziegenk\u00e4se und Pistou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/#website\",\"url\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/\",\"name\":\"Les D\u00e9lices de Provence\",\"description\":\"Epicerie fine en ligne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616\",\"name\":\"Delices_Provence\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g\",\"caption\":\"Delices_Provence\"},\"sameAs\":[\"https:\/\/www.aromeprod2.com\"],\"url\":\"https:\/\/www.lesdelicesdeprovence.ch\/de\/author\/delices_provence\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence","description":"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/","og_locale":"de_DE","og_type":"article","og_title":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence","og_description":"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,","og_url":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/","og_site_name":"Les D\u00e9lices de Provence","article_published_time":"2022-11-23T14:10:57+00:00","article_modified_time":"2024-03-28T13:40:52+00:00","og_image":[{"width":422,"height":422,"url":"http:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg","type":"image\/jpeg"}],"author":"Delices_Provence","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Delices_Provence","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#article","isPartOf":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/"},"author":{"name":"Delices_Provence","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616"},"headline":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou","datePublished":"2022-11-23T14:10:57+00:00","dateModified":"2024-03-28T13:40:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/"},"wordCount":104,"image":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg","keywords":["Basilikumstempel"],"articleSection":["Rezept","salzig"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/","url":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/","name":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou - Les D\u00e9lices de Provence","isPartOf":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage"},"image":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg","datePublished":"2022-11-23T14:10:57+00:00","dateModified":"2024-03-28T13:40:52+00:00","author":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616"},"description":"Von Colette, Lausanne Zutaten (f\u00fcr 4 Personen) : - Ein Pfund Zucchini - 2 frische Ziegen (am besten handwerklich) - 1 Glas Basilikum-Pistou 130g - Salz,","breadcrumb":{"@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#primaryimage","url":"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg","contentUrl":"https:\/\/www.lesdelicesdeprovence.ch\/wp-content\/uploads\/2022\/11\/tian_courgette_chevre_2.jpg","width":422,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/zucchini-tian-mit-ziegenkaese-und-pesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accoglienza","item":"https:\/\/www.lesdelicesdeprovence.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Zucchini-Tian mit Ziegenk\u00e4se und Pistou"}]},{"@type":"WebSite","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/#website","url":"https:\/\/www.lesdelicesdeprovence.ch\/de\/","name":"Les D\u00e9lices de Provence","description":"Epicerie fine en ligne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesdelicesdeprovence.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.lesdelicesdeprovence.ch\/de\/#\/schema\/person\/714ac515a40dce8ba1538b8bb745f616","name":"Delices_Provence","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cafe2f8945ae101ef11b4f4bf966ed256c7d66c3a892530540eae920b13fe242?s=96&d=mm&r=g","caption":"Delices_Provence"},"sameAs":["https:\/\/www.aromeprod2.com"],"url":"https:\/\/www.lesdelicesdeprovence.ch\/de\/author\/delices_provence\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/posts\/8783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/comments?post=8783"}],"version-history":[{"count":2,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/posts\/8783\/revisions"}],"predecessor-version":[{"id":12500,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/posts\/8783\/revisions\/12500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/media\/8760"}],"wp:attachment":[{"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/media?parent=8783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/categories?post=8783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesdelicesdeprovence.ch\/de\/wp-json\/wp\/v2\/tags?post=8783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}